{"id":55539,"date":"2026-03-09T16:40:43","date_gmt":"2026-03-09T15:40:43","guid":{"rendered":"https:\/\/abi-newsite.azurewebsites.net\/?p=55539"},"modified":"2026-03-11T17:01:51","modified_gmt":"2026-03-11T16:01:51","slug":"il-senso-dellarte-per-la-cura-di-ildegarda-ferraro","status":"publish","type":"post","link":"https:\/\/www.abi.it\/en\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/","title":{"rendered":"Il senso dell\u2019arte per la cura di Ildegarda Ferraro"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"55539\" class=\"elementor elementor-55539\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a8a5f1 e-flex e-con-boxed e-con e-parent\" data-id=\"5a8a5f1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8a36526 e-con-full elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con e-child\" data-id=\"8a36526\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff9fd06 e-con-full e-flex e-con e-child\" data-id=\"ff9fd06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<article class=\"elementor-element elementor-element-6f09580 section e-con-full e-flex e-con e-child\" data-id=\"6f09580\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-589e382 elementor-widget elementor-widget-heading\" data-id=\"589e382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Il senso dell\u2019arte per la cura<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5991dc elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d5991dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p class=\"xmsonormal\" style=\"margin: 0cm\"><strong>Ildegarda Ferraro<\/strong>, ABI<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed2499 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"8ed2499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Arte e cultura sono alla base della crescita personale e sociale. Le ultime ricerche confermano anche che sono una via per la salute, per mantenersi in buona forma, ma anche proprio per rimettersi e rendere pi\u00f9 efficace la ripresa psico fisica in caso di malattie. Insomma, sostengono e aiutano la cura. Si parla di \u00abart cure\u00bb e di \u00abart therapy\u00bb. La cultura sostiene la salute e la salute a sua volta spinge l\u2019arte. Il tema \u00e8 ampiamente affrontato in ambito internazionale dall\u2019Organizzazione mondiale della sanit\u00e0 (Oms), ma anche in Italia ci sono esperienze significative, tenute in ampia considerazione dal Ministero della Cultura (Mic). Molti i casi concreti, a partire dai musei, che non sono solo musei, ma centri di aggregazione e di iniziative di educazione e di salute anche per malattie invalidanti. E poi ovviamente agli ospedali, come il Sant\u2019Andrea di Roma o anche in centri minori, che riconoscono nell\u2019arte una forza se non proprio salvifica sicuramente di aiuto. In molti paesi \u00e8 ormai accreditata la \u00abprescrizione sociale\u00bb per venire incontro a bisogni specifici. Intanto <em>is culture!<\/em>, il Festival promosso da ABI e Acri, con le iniziative delle banche e fondazioni, sotto l\u2019alto patronato del Presidente della Repubblica, anche quest\u2019anno mette a disposizione un ricco palinsesto per tutti in tutta Italia.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99a0cdc elementor-widget elementor-widget-heading\" data-id=\"99a0cdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00abArt cure\u00bb e Rapporto Oms<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d32b19c elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d32b19c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Se ne parla da molto. Una nuova spinta scientifica viene dal libro Art cure: The Science of How the Art Transform Our Health di Daisy Fancourt, direttrice del Collaborating Centre for Arts &amp; Health dell\u2019Organizzazione mondiale della sanit\u00e0, e professoressa di psicobiologia e epidemiologia allo University College di Londra. Fancourt ha curato il Rapporto dell\u2019Oms \u00abQuali sono le evidenze sul ruolo delle arti nel miglioramento della salute e del benessere?\u00bb con i risultati di 3.000 studi che, come riporta il documento, \u00abhanno messo in evidenza il ruolo determinante delle arti per quanto riguarda la prevenzione delle malattie, la promozione della salute e il trattamento e la gestione delle patologie che si manifestano nel corso della vita\u00bb. L\u2019arte e la cultura in termini pi\u00f9 generali aiutano la cura, ma sono anche una efficace cassetta degli attrezzi di benessere e prevenzione. Alla base un concetto di salute che non \u00e8 solo assenza di malattia, ma pienezza di vita.<br \/>I risultati del Rapporto sottolineano un potenziale impatto delle arti sia sulla salute mentale che su quella fisica. Due le categorie tematiche: prevenzione e promozione, gestione e trattamento.<br \/>Per quanto riguarda il primo ambito, l\u2019indagine riporta che \u00able arti possono: influenzare i determinanti sociali della salute; sostenere lo sviluppo del bambino; incoraggiare comportamenti che promuovono la salute; aiutare a prevenire le malattie; supportare l\u2019assistenza e la cura\u00bb. Per gestione e trattamento, invece, \u00abpossono: aiutare le persone che soffrono di malattie mentali; sostenere le cure per le persone in condizioni acute; sostenere le persone con disturbi neuroevolutivi e neurologici; contribuire al trattamento di malattie croniche degenerative; concorrere all\u2019assistenza nel fine vita\u00bb.<br \/>Il Rapporto Oms si occupa di cinque ampie categorie:<br \/>\u00ab- le arti performative (ad esempio teatro,<br \/>danza, canto, musica, film);<br \/>&#8211; le arti visive, il design e l\u2019artigianato (pittura, fotografia, scultura, tessile e altri prodotti di design e dell\u2019artigianato);<br \/>&#8211; la letteratura (scrittura, lettura, partecipazione a festival letterari);<br \/>&#8211; la cultura (musei, gallerie, mostre d\u2019arte, concerti, teatro, eventi comunitari, festival<br \/>e fiere culturali);<br \/>&#8211; le arti online, digitali ed elettroniche (animazioni, film-making, computer grafica).<br \/>Queste categorie combinano sia un coinvolgimento attivo che uno ricettivo e, soprattutto, trascendono i confini culturali e racchiudono in s\u00e9 la flessibilit\u00e0 necessaria per consentire lo sviluppo di nuove forme d\u2019arte, come dimostrato dallo sviluppo delle arti online, digitali ed elettroniche\u00bb.<br \/>Alla base, come si diceva un concetto di salute molto ampio, inteso come \u00abuno stato di completo benessere fisico, mentale e sociale, e non la mera assenza di malattia o infermit\u00e0\u00bb, tanto da renderla radicata profondamente nella societ\u00e0 e nella cultura. Inoltre, l\u2019Oms pone l\u2019accento sull\u2019importanza della prevenzione delle malattie e, di conseguenza, su quanto \u00e8 determinante per salute.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad7ea0 elementor-widget elementor-widget-heading\" data-id=\"9ad7ea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Manuale di \u00abprescrizione\nsociale\u00bb<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d40aa elementor-widget elementor-widget-pxl_text_editor\" data-id=\"59d40aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Quello che conta \u00e8 attivare procedure che inneschino benessere. Non solo quindi farmaci e cure, ma \u00abprescrizioni sociali\u00bb, che possono agire profondamente sul quadro generale. Sempre l\u2019Organizzazione mondiale della sanit\u00e0 ha pubblicato un vero e proprio manuale in questo campo. Le indicazioni sono chiare: \u00abLa prescrizione sociale si basa sulle evidenze dell\u2019impatto dei fattori socioeconomici sulla salute e sulla rilevanza dei<br \/>determinanti sociali, cruciali per migliorare gli esiti di salute. L\u2019obiettivo \u00e8 favorire la promozione del benessere dei cittadini da parte dei professionisti sanitari anche attraverso le risorse di carattere sociale, culturale, sportive presenti e attive nella comunit\u00e0 locale\u00bb.<br \/>L\u2019idea \u00e8 che insieme a indicazioni fisiche, come regime alimentare e movimento, componenti culturali e artistiche possano innescare reazioni benefiche sostanziali. Va da s\u00e9 che tutto ci\u00f2 pu\u00f2 essere positivo per tutti, ma le persone pi\u00f9 fragili sono quelle che possono averne maggiori benefici(1).<br \/>Tra i percorsi pilota in Italia citati dal manuale<br \/>&#8211; la rete di Mta (Musei Toscana per l\u2019Alzheimer);<br \/>&#8211; il progetto nazionale \u00abNati per Leggere\u00bb;<br \/>&#8211; il programma nazionale \u00abDance Well\u00bb per le persone con il Parkinson;<br \/>&#8211; la rete \u00abArchivi e salute\u00bb che ha avviato una sperimentazione di prescrizione sociale creativa per anziani con demenza e Alzheimer;<br \/>&#8211; lo studio multinazionale coordinato dall\u2019Oms, \u00abMusic and Motherhood\u00bb, per il sostegno alla depressione post partum.<br \/>Sono partner di Cultural Welfare Center in questo percorso la Fondazione Compagnia di San Paolo (Obiettivo Cultura, progetto Well Impact) e la Fondazione Monte dei Paschi di Siena (C-Hub Culture ibride).<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b98a35 elementor-widget elementor-widget-heading\" data-id=\"0b98a35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Il Ministero della Cultura e\nl\u2019arte che cura<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd0e1a elementor-widget elementor-widget-pxl_text_editor\" data-id=\"7fd0e1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Il tema \u00e8 ormai parte dei percorsi istituzionali accreditati. Il Mic ha dedicato a questo nuovo approccio ampio spazio e un convegno specifico per fare il punto e declinare con esperti del mondo artistico, medico scientifico ed economico le esperienze gi\u00e0 in campo in Italia e all\u2019estero. La prospettiva \u00e8 di strutturare e normare le pratiche terapeutiche legate all\u2019arte, trasformandole in politiche intersettoriali fondate su evidenze scientifiche.<br \/>Di grande interesse anche la formazione, con figure professionali da affiancare a medici e studiosi di arte, per esempio psicologi, terapisti e sociologhi, e personale specializzato per creare contesti utili tra cultura e salute.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4304b19 elementor-widget elementor-widget-heading\" data-id=\"4304b19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Musei non solo musei<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d3005a elementor-widget elementor-widget-pxl_text_editor\" data-id=\"5d3005a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Va da s\u00e9 che i primi centri strutturati da cui si parte sono i musei, che assumono la forma sostanziale di centri di aggregazione, di presidio civico, di sviluppo culturale e educativo, di sostegno sanitario anche per i pi\u00f9 fragili.<br \/>Moltissime le esperienze in campo: gli Uffizi, Galleria Borghese, il Parco del Colosseo, il Museo etrusco di Villa Giulia, le Residenze sabaude hanno progetti specifici e sono parte di un movimento che sta cambiando l\u2019identit\u00e0 dei musei. Si va da iniziative per il Parkinson, per l\u2019Alzheimer, fino a progetti per disabilit\u00e0 grave. Musei quindi non solo quindi luoghi di conservazione e di bellezza, ma anche aggregazione e di cura. Le esperienze sono bellissime, basti pensare a \u00abDance Well\u00bb per il Parkinson del Museo etrusco di Villa Giulia con movimenti ispirati alla ceramica antica, oppure a Salus per Artem del parco Archeologico del Colosseo, che rende accessibile luoghi bellissimi a chi per disabilit\u00e0 o vulnerabilit\u00e0 sociale non pu\u00f2 normalmente esserci.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0540ac4 elementor-widget elementor-widget-heading\" data-id=\"0540ac4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Il welfare culturale<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e1ba54 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"0e1ba54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Non solo quindi cura come prevenzione o azione per il recupero, ma anche come crescita personale e sociale. E le risposte sono sostanziali. Le prime stime evidenziano che<br \/>si pu\u00f2 immaginare una sopravvivenza maggiore dell\u201980% per chi vive culturalmente pienamente.<br \/>Si consolida il welfare culturale, inteso come modello integrato di promozione del benessere e della salute, basato anche sule arti visive, performative e sul patrimonio culturale.<br \/>Le esperienze si moltiplicano. A Pistoia \u00abVitamina T &#8211; come Teatro\u00bb si occupa di benessere dei bambini e delle famiglie, i biglietti si comprano in farmacia e vengono poi convertiti a teatro. \u00abSciroppo di teatro\u00bb \u00e8 invece un progetto di welfare culturale in Emilia Romagna con l\u2019idea di fondo che il teatro possa essere prescritto dai pediatri come parte della cura per i bambini.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46ff7b9 elementor-widget elementor-widget-heading\" data-id=\"46ff7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ospedali in primo piano<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a952e1e elementor-widget elementor-widget-pxl_text_editor\" data-id=\"a952e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Se da una parte i musei diventano un punto di attenzione non solo artistico, dall\u2019altro gli ospedali cominciano a fare tesoro di queste nuove prospettive. L\u2019arte riduce lo stress e anche nelle situazioni pi\u00f9 difficili aiuta in maniera evidente. Di qui esperienze innovative anche in reparti oncologici, iniziative importanti o sezioni pediatriche, ristruttura zioni ambientali per trasformare i centri di cura in luoghi di bellezza.<br \/>Le sperimentazioni si moltiplicano in Italia e all\u2019estero. E cos\u00ec l\u2019ospedale Sant\u2019Andrea di Roma utilizza l\u2019arte per migliorare il benessere psicofisico dei pazienti; il Centro oncologico dell\u2019Isola Tiberina-Gemelli a Roma ha attivato iniziative artistiche e ristrutturato aree archeologiche; a Milano il Mapp, il Museo di arte contemporanea nell\u2019ex ospedale psichiatrico, ha iniziative anche per pazienti; l\u2019ospedale di Pagani vicino Salerno segue protocolli specifici sull\u2019arte che cura; gli ospedali di Cosenza e di Salerno hanno chiamato artisti per mettere le loro opere a<br \/>disposizione a disposizione. Anche in piccoli centri sono vive esperienze interessanti, come a Vetralla in provincia di Viterbo dove il Centro di salute mentale ha attivato un progetto per trasformare gli spazi in una collezione permanente d\u2019arte.<br \/>I casi all\u2019estero sono molto numerosi, Canada e Uk hanno vaste esperienze. E l\u2019arte che cura \u00e8 una pratica importante anche per i medici e il personale sanitario tutto. Lo stress e il burn out sono spesso una prospettiva tangibile. Di qui iniziative legate all\u2019arte per scaricare la tensione e disattivare queste ipotesi.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a674d4 elementor-widget elementor-widget-heading\" data-id=\"3a674d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Metriche<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f6a3e9 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"0f6a3e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>Va da s\u00e9 che quello che pu\u00f2 fare la differenza \u00e8 la misurazione. Indagini sul campo in Uk evidenziano che 1 sterlina investita in \u00abart therapy\u00bb prevede un ritorno da 2 a 8 sterline.<br \/>In Kenia, in situazioni molto disagiate con due psichiatri infantili per 13 milioni di abitanti, esperienze di terapia d\u2019arte anche marginali nelle scuole hanno avuto risultati tangibili. D\u2019altra parte, anche da noi, si stima che 1 su 5 appuntamenti dal medico \u00e8 collegato a problemi non medici, inclusi isolamento, solitudine, depressione relazioni e stress. L\u2019isolamento sociale e la solitudine hanno impatti negativi sulla speranza di vita e possono influire sulla salute cardiovascolare, e avere effetti in termini di depressione e rischi di demenza. In Italia la naturale socievolezza aiuta, ma anche qui la prospettiva va cambiando, si stima che 1 persona su 5 oltre i 75 anni viva sola e che dai 65 anni il declino \u00e8 emergente.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d2f4f elementor-widget elementor-widget-heading\" data-id=\"e3d2f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Il Festival \u00e8 cultura!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1d75ea elementor-widget elementor-widget-pxl_text_editor\" data-id=\"d1d75ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>In questo contesto anche il Festival <em>is culture! <\/em>pu\u00f2 portare il suo contributo. Promosso da ABI e Acri, con la partecipazione di banche e fondazioni, mette a disposizione un panorama di eventi tutto l\u2019anno, con particolare attenzione a una settimana precisa di particolare attenzione. L\u2019iniziativa si svolge sotto l\u2019Alto Patronato del Presidente della Repubblica Italiana, con il patrocinio della Commissione Nazionale Italiana per l\u2019Unesco, del Ministero del Turismo, dell\u2019Associazione Nazionale Comuni Italiani (Anci), dell\u2019Associazione Dimore Storiche Italiane, dell\u2019Accademia di Belle Arti di Roma e del Touring Club Italiano.<br \/>Tutte le informazioni sono sempre disponibili sul sito della manifestazione. Tutto questo <em>is culture!<\/em>. Ed \u00e8 pure benessere e salute.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f021049 elementor-widget elementor-widget-heading\" data-id=\"f021049\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Note<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b59ecf elementor-widget elementor-widget-pxl_text_editor\" data-id=\"0b59ecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t<p>1 Per favorire la diffusione del modello nel nostro Paese, l\u2019Istituto Superiore di Sanit\u00e0 (Iss), il Cultural Welfare Center (Ccw) e il Centro regionale di Documentazione per la Promozione della Salute Regione Piemonte (DoRS), in collaborazione con il Centro Bach-Universit\u00e0 di Chieti e Pescara, il Centro per la Salute del Bambino (Csb) e la Fondazione Medicina a Misura di Donna, hanno curato la traduzione italiana del documento.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01a2894 elementor-widget elementor-widget-heading\" data-id=\"01a2894\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Versione PDF<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80caa1c elementor-widget elementor-widget-shortcode\" data-id=\"80caa1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='w3eden'><!-- WPDM Link Template: Call to Action 3 -->\n<div class=\"well c2a3\">\n        <div class=\"media\">\n          <div class=\"mr-3\" align=\"left\">\n            <!-- <a\n              href=\"https:\/\/www.abi.it\/en\/download\/febbraio-2026-il-senso-dellarte-per-la-cura-ildegarda-ferraro\/?wpdmdl=55592&refresh=6a045d4c879141778670924\"\n              role=\"button\"\n              aria-label=\"download file\"\n              aria-hidden=\"true\"\n            > -->\n              <svg\n                width=\"56\"\n                height=\"67\"\n                viewbox=\"0 0 56 67\"\n                fill=\"none\"\n                xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n              >\n                <circle\n                  cx=\"27.5772\"\n                  cy=\"33.4703\"\n                  r=\"19\"\n                  transform=\"rotate(-45 27.5772 33.4703)\"\n                  fill=\"white\"\n                  stroke=\"#1E5580\"\n                \/>\n                <mask\n                  id=\"mask0_3240_9322\"\n                  style=\"mask-type: alpha\"\n                  maskunits=\"userSpaceOnUse\"\n                  x=\"15\"\n                  y=\"21\"\n                  width=\"25\"\n                  height=\"25\"\n                >\n                  <rect\n                    x=\"15.7393\"\n                    y=\"21.3075\"\n                    width=\"24\"\n                    height=\"24\"\n                    fill=\"#D9D9D9\"\n                  \/>\n                <\/mask>\n                <g mask=\"url(#mask0_3240_9322)\">\n                  <path\n                    d=\"M27.7393 36.8845L24.2008 33.346L24.9085 32.6267L27.2393 34.9575V26.3075H28.2393V34.9575L30.57 32.6267L31.2778 33.346L27.7393 36.8845ZM22.3548 40.3075C21.8944 40.3075 21.5101 40.1533 21.2018 39.845C20.8934 39.5367 20.7393 39.1523 20.7393 38.692V36.269H21.7393V38.692C21.7393 38.846 21.8033 38.9871 21.9315 39.1152C22.0597 39.2434 22.2008 39.3075 22.3548 39.3075H33.1238C33.2778 39.3075 33.4188 39.2434 33.547 39.1152C33.6752 38.9871 33.7393 38.846 33.7393 38.692V36.269H34.7393V38.692C34.7393 39.1523 34.5851 39.5367 34.2768 39.845C33.9684 40.1533 33.5841 40.3075 33.1238 40.3075H22.3548Z\"\n                    fill=\"#1E5580\"\n                  \/>\n                <\/g>\n              <\/svg>\n            <!-- <\/a> -->\n          <\/div>\n          <div class=\"media-body\">\n            <p\n              class=\"media-heading\"\n              style=\"                padding-top: 0px;                border: 0px;                margin: 0 0 5px 0;                font-size: 12pt;              \"\n            >\n              <a style=\"font-weight: 700\" href=\"https:\/\/www.abi.it\/en\/download\/febbraio-2026-il-senso-dellarte-per-la-cura-ildegarda-ferraro\/?wpdmdl=55592&refresh=6a045d4c879141778670924\">FEBBRAIO 2026 - Il senso dell\u2019arte per la cura - Ildegarda Ferraro<\/a>\n            <\/p>\n            \n              \n            <div class=\"counters\">\n                <span\n                    style=\"font-size: 14px !important; font-weight: 400;\"\n                    class=\"text-muted ml-4\"\n                > \n                <\/span>\n              <span\n                style=\"font-size: 13px !important; font-weight: 300\"\n                class=\"text-muted ml-4\"\n              > 10 March 2026\n              <\/span>\n            <\/div>\n \n            <!--...-->\n          <\/div>\n          <!--\n    <div class=\"ml-3\" align=\"right\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.abi.it\/en\/download\/febbraio-2026-il-senso-dellarte-per-la-cura-ildegarda-ferraro\/?wpdmdl=55592&refresh=6a045d4c879141778670924\">Download<\/a>\n    <\/div>\n            -->\n        <\/div>\n      <\/div>\n \n      <style>\n        .well.c2a3 {\n          font-family: 'Mulish' !important;\n          background-color: white !important;\n          height: auto !important;\n          margin-bottom: 0px !important;\n        }\n        \n        .well.c2a3 .btn {\n          padding: 11px 30px;\n          font-size: 11pt;\n        }\n        \n        .text-muted.ml-4 p {\n            margin-bottom: 0px !important;\n        }\n \n        .well.c2a3 .media-body {\n          font-size: 11pt;\n          \/*To take the full width on mobile screen*\/\n          min-width: 300px;\n        }\n \n        .well.c2a3 .wpdm_icon {\n          height: 42px;\n          width: auto;\n        }\n        .media {\n          display: flex;\n          align-items: center !important;\n        }\n        .media-heading a {\n          color: #074973 !important;\n        }\n        .counters {\n          display: flex;\n          flex-direction: column !important;\n          justify-content: flex-start !important;\n        }\n        .text-muted.ml-4 {\n          margin-left: 0px !important;\n          margin-bottom: 5px !important;\n        }\n      <\/style>\n\n<!--\n<div class=\"well c2a3\">\n    <div class=\"media\">\n        <div class=\"mr-3\" align=\"left\">\n            <img decoding=\"async\" class=\"wpdm_icon\" alt=\"Icon\" src=\"\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/>\n        <\/div>\n        <div class=\"media-body\">\n            <h3 class=\"media-heading\" style=\"padding-top: 0px;border:0px;margin: 0 0 5px 0;font-size:12pt;\">\n                <a style=\"font-weight: 700\" href=\"https:\/\/www.abi.it\/en\/download\/febbraio-2026-il-senso-dellarte-per-la-cura-ildegarda-ferraro\/\">FEBBRAIO 2026 - Il senso dell\u2019arte per la cura - Ildegarda Ferraro<\/a>\n                <span style=\"font-size:8pt;font-weight:300\" class=\"text-muted ml-4\">\n                    <i class=\"fas fa-hdd mr-1\"><\/i> 65.77 KB\n                    <i class=\"ml-3 far fa-arrow-alt-circle-down mr-1\"><\/i> 153 downloads\n                <\/span>\n            <\/h3>\n            ...\n        <\/div>\n        <div class=\"ml-3\" align=\"right\">\n            <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.abi.it\/en\/download\/febbraio-2026-il-senso-dellarte-per-la-cura-ildegarda-ferraro\/?wpdmdl=55592&refresh=6a045d4c879141778670924\">Download<\/a>\n        <\/div>\n    <\/div>\n\n<\/div>\n-->\n<!--\n<style>\n    .well.c2a3 .btn {\n        padding: 11px 30px;\n        font-size: 11pt;\n    }\n\n    .well.c2a3 .media-body {\n        font-size: 11pt;\n    }\n\n    .well.c2a3 .wpdm_icon {\n        height: 42px;\n        width: auto;\n    }<\/style>\n--><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc901da elementor-widget elementor-widget-pxl_button\" data-id=\"cc901da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-button\">\n    <div class=\"pxl-item--container\">\n        <div class=\"pxl-item--inner\">\n            <a class=\"btn pxl-item--button pxl-btn-default pxl-btn-large pxl-btn-border pxl-btn-dark  pxl-hover-default\" href=\"https:\/\/www.bancaria.it\/\" data-wow-delay=\"ms\" data-text=\"Vai al sito di Bancaria\">\n                <span class=\"pxl-btn--text\">Vai al sito di Bancaria<\/span>\n                            <\/a>\n        <\/div>\n    <\/div>\n<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3cecc3 elementor-widget elementor-widget-pxl_divider\" data-id=\"d3cecc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-divider  pxl-particle-right none none\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dae9a8d e-con-full elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con e-child\" data-id=\"dae9a8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Arte e cultura sono alla base della crescita personale e sociale. Le ultime ricerche confermano anche che sono una via per la salute, per mantenersi in buona forma, ma anche proprio per rimettersi e rendere pi\u00f9 efficace la ripresa psico fisica in caso di malattie. Insomma, sostengono e aiutano la cura. Si parla di \u00abart cure\u00bb e di \u00abart therapy\u00bb. La cultura sostiene la salute e la salute a sua volta spinge l&#8217;arte. Il tema \u00e8 ampiamente affrontato in ambito internazionale dall&#8217;Organizzazione mondiale della sanit\u00e0 (Oms), ma anche in Italia ci sono esperienze significative, tenute in ampia considerazione dal Ministero della Cultura (Mic).<\/p>","protected":false},"author":21,"featured_media":55667,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[313,314],"tags":[],"class_list":["post-55539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articoli-bancaria","category-febbraio-2026"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il senso dell\u2019arte per la cura di Ildegarda Ferraro - ABI - Associazione Bancaria Italiana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abi.it\/en\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il senso dell\u2019arte per la cura di Ildegarda Ferraro - ABI - Associazione Bancaria Italiana\" \/>\n<meta property=\"og:description\" content=\"Arte e cultura sono alla base della crescita personale e sociale. Le ultime ricerche confermano anche che sono una via per la salute, per mantenersi in buona forma, ma anche proprio per rimettersi e rendere pi\u00f9 efficace la ripresa psico fisica in caso di malattie. Insomma, sostengono e aiutano la cura. Si parla di \u00abart cure\u00bb e di \u00abart therapy\u00bb. La cultura sostiene la salute e la salute a sua volta spinge l&#039;arte. Il tema \u00e8 ampiamente affrontato in ambito internazionale dall&#039;Organizzazione mondiale della sanit\u00e0 (Oms), ma anche in Italia ci sono esperienze significative, tenute in ampia considerazione dal Ministero della Cultura (Mic).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abi.it\/en\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\" \/>\n<meta property=\"og:site_name\" content=\"ABI - Associazione Bancaria Italiana\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-09T15:40:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T16:01:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abi.it\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"d.mattasoglio@abi.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"d.mattasoglio@abi.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\"},\"author\":{\"name\":\"d.mattasoglio@abi.it\",\"@id\":\"https:\/\/www.abi.it\/#\/schema\/person\/c819655150d388d2db8ee645a9f997bf\"},\"headline\":\"Il senso dell\u2019arte per la cura di Ildegarda Ferraro\",\"datePublished\":\"2026-03-09T15:40:43+00:00\",\"dateModified\":\"2026-03-11T16:01:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\"},\"wordCount\":1940,\"image\":{\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage\"},\"thumbnailUrl\":\"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg\",\"articleSection\":[\"Articoli Bancaria\",\"Febbraio 2026\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\",\"url\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\",\"name\":\"Il senso dell\u2019arte per la cura di Ildegarda Ferraro - ABI - Associazione Bancaria Italiana\",\"isPartOf\":{\"@id\":\"https:\/\/www.abi.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage\"},\"thumbnailUrl\":\"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg\",\"datePublished\":\"2026-03-09T15:40:43+00:00\",\"dateModified\":\"2026-03-11T16:01:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.abi.it\/#\/schema\/person\/c819655150d388d2db8ee645a9f997bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage\",\"url\":\"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg\",\"contentUrl\":\"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg\",\"width\":1600,\"height\":812},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/abi-newsite.azurewebsites.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il senso dell\u2019arte per la cura di Ildegarda Ferraro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.abi.it\/#website\",\"url\":\"https:\/\/www.abi.it\/\",\"name\":\"ABI - Associazione Bancaria Italiana\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.abi.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.abi.it\/#\/schema\/person\/c819655150d388d2db8ee645a9f997bf\",\"name\":\"d.mattasoglio@abi.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/7acddfdf4aed6cd039f90374431de0ae3c15ec50affca2b29c841f3f5b4c727d?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7acddfdf4aed6cd039f90374431de0ae3c15ec50affca2b29c841f3f5b4c727d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7acddfdf4aed6cd039f90374431de0ae3c15ec50affca2b29c841f3f5b4c727d?s=96&d=mm&r=g\",\"caption\":\"d.mattasoglio@abi.it\"},\"url\":\"https:\/\/www.abi.it\/en\/author\/d-mattasoglioabi-it\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il senso dell\u2019arte per la cura di Ildegarda Ferraro - ABI - Associazione Bancaria Italiana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abi.it\/en\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/","og_locale":"en_GB","og_type":"article","og_title":"Il senso dell\u2019arte per la cura di Ildegarda Ferraro - ABI - Associazione Bancaria Italiana","og_description":"Arte e cultura sono alla base della crescita personale e sociale. Le ultime ricerche confermano anche che sono una via per la salute, per mantenersi in buona forma, ma anche proprio per rimettersi e rendere pi\u00f9 efficace la ripresa psico fisica in caso di malattie. Insomma, sostengono e aiutano la cura. Si parla di \u00abart cure\u00bb e di \u00abart therapy\u00bb. La cultura sostiene la salute e la salute a sua volta spinge l'arte. Il tema \u00e8 ampiamente affrontato in ambito internazionale dall'Organizzazione mondiale della sanit\u00e0 (Oms), ma anche in Italia ci sono esperienze significative, tenute in ampia considerazione dal Ministero della Cultura (Mic).","og_url":"https:\/\/www.abi.it\/en\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/","og_site_name":"ABI - Associazione Bancaria Italiana","article_published_time":"2026-03-09T15:40:43+00:00","article_modified_time":"2026-03-11T16:01:51+00:00","og_image":[{"width":1600,"height":812,"url":"https:\/\/www.abi.it\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg","type":"image\/jpeg"}],"author":"d.mattasoglio@abi.it","twitter_card":"summary_large_image","twitter_misc":{"Written by":"d.mattasoglio@abi.it","Estimated reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#article","isPartOf":{"@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/"},"author":{"name":"d.mattasoglio@abi.it","@id":"https:\/\/www.abi.it\/#\/schema\/person\/c819655150d388d2db8ee645a9f997bf"},"headline":"Il senso dell\u2019arte per la cura di Ildegarda Ferraro","datePublished":"2026-03-09T15:40:43+00:00","dateModified":"2026-03-11T16:01:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/"},"wordCount":1940,"image":{"@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg","articleSection":["Articoli Bancaria","Febbraio 2026"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/","url":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/","name":"Il senso dell\u2019arte per la cura di Ildegarda Ferraro - ABI - Associazione Bancaria Italiana","isPartOf":{"@id":"https:\/\/www.abi.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage"},"image":{"@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg","datePublished":"2026-03-09T15:40:43+00:00","dateModified":"2026-03-11T16:01:51+00:00","author":{"@id":"https:\/\/www.abi.it\/#\/schema\/person\/c819655150d388d2db8ee645a9f997bf"},"breadcrumb":{"@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#primaryimage","url":"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg","contentUrl":"\/wp-content\/uploads\/2026\/03\/2026-Copertine-Sito-Bancaria-72dpi-1600x812-1.jpg","width":1600,"height":812},{"@type":"BreadcrumbList","@id":"https:\/\/www.abi.it\/il-senso-dellarte-per-la-cura-di-ildegarda-ferraro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abi-newsite.azurewebsites.net\/"},{"@type":"ListItem","position":2,"name":"Il senso dell\u2019arte per la cura di Ildegarda Ferraro"}]},{"@type":"WebSite","@id":"https:\/\/www.abi.it\/#website","url":"https:\/\/www.abi.it\/","name":"ABI - Italian Banking Association","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.abi.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.abi.it\/#\/schema\/person\/c819655150d388d2db8ee645a9f997bf","name":"d.mattasoglio@abi.it","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/7acddfdf4aed6cd039f90374431de0ae3c15ec50affca2b29c841f3f5b4c727d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7acddfdf4aed6cd039f90374431de0ae3c15ec50affca2b29c841f3f5b4c727d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7acddfdf4aed6cd039f90374431de0ae3c15ec50affca2b29c841f3f5b4c727d?s=96&d=mm&r=g","caption":"d.mattasoglio@abi.it"},"url":"https:\/\/www.abi.it\/en\/author\/d-mattasoglioabi-it\/"}]}},"_links":{"self":[{"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/posts\/55539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/comments?post=55539"}],"version-history":[{"count":38,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/posts\/55539\/revisions"}],"predecessor-version":[{"id":55628,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/posts\/55539\/revisions\/55628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/media\/55667"}],"wp:attachment":[{"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/media?parent=55539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/categories?post=55539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.abi.it\/en\/wp-json\/wp\/v2\/tags?post=55539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}